{"id":1611,"date":"2022-08-09T14:48:02","date_gmt":"2022-08-09T17:48:02","guid":{"rendered":"http:\/\/autocarmulti.com.br\/?post_type=product&#038;p=1611"},"modified":"2022-08-09T14:48:02","modified_gmt":"2022-08-09T17:48:02","slug":"kia-sorento-2-4-ex-2011","status":"publish","type":"product","link":"https:\/\/autocarmulti.com.br\/index.php\/produto\/kia-sorento-2-4-ex-2011\/","title":{"rendered":"KIA SORENTO 2.4 EX 2011"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>VE\u00cdCULO ACIMA DA MEDIA<\/p>\n<p>4 PNEUS NOVOS NA GARANTIA<\/p>\n<p>MANUAL E CHAVE RESERVA<\/p>\n<p>LAUDO CAUTELAR APROVADO<\/p>\n","protected":false},"featured_media":1615,"template":"","meta":[],"_links":{"self":[{"href":"https:\/\/autocarmulti.com.br\/index.php\/wp-json\/wp\/v2\/product\/1611"}],"collection":[{"href":"https:\/\/autocarmulti.com.br\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/autocarmulti.com.br\/index.php\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/autocarmulti.com.br\/index.php\/wp-json\/wp\/v2\/media\/1615"}],"wp:attachment":[{"href":"https:\/\/autocarmulti.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}